{"id":135573,"date":"2026-04-27T04:59:27","date_gmt":"2026-04-27T10:59:27","guid":{"rendered":"https:\/\/pongara.net\/news\/benediction-pierde-a-dave-ingram-para-la-gira-espanola-oscar-rilo-sera-su-sustituto\/"},"modified":"2026-04-27T04:59:27","modified_gmt":"2026-04-27T10:59:27","slug":"benediction-pierde-a-dave-ingram-para-la-gira-espanola-oscar-rilo-sera-su-sustituto","status":"publish","type":"post","link":"https:\/\/pongara.net\/news\/benediction-pierde-a-dave-ingram-para-la-gira-espanola-oscar-rilo-sera-su-sustituto\/","title":{"rendered":"BENEDICTION pierde a Dave Ingram para la gira espa\u00f1ola: \u00d3scar Rilo ser\u00e1 su sustituto"},"content":{"rendered":"<div>\n<p><img width=\"200\" height=\"200\" src=\"https:\/\/pongara.net\/news\/wp-content\/uploads\/2026\/04\/benediction-2019-200x200-1.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"La banda de Death Metal BENEDICTION\" style=\"float:left; padding:2px; margin:0 15px 10px 0; background-color: #ffffff; -moz-border-radius: 2px; -webkit-border-radius: 2px; box-shadow: 0 0 2px #B5B5B5; -moz-box-shadow: 0 0 2px #b5b5b5; -webkit-box-shadow: 0 0 2px #B5B5B5; border-image-width: 1px; outline-width: medium;\" decoding=\"async\" loading=\"lazy\">Problemas de salud aquejan al cantante del grupo de Death Metal Los brit\u00e1nicos BENEDICTION han informado de que su vocalista, Dave Ingram, no podr\u00e1 actuar en los conciertos programados para Madrid, Valencia y Barcelona. Su ausencia en las actuaciones es debida a problemas de salud. Su sustituto es el coru\u00f1\u00e9s \u00d3scar Rilo, de DARK EMBRACE, [\u2026]<\/p>\n<p>La entrada <a href=\"https:\/\/www.hellpress.com\/noticias\/benediction-pierde-dave-ingram-gira-espanola-oscar-rilo-sustituto\/\">BENEDICTION pierde a Dave Ingram para la gira espa\u00f1ola: \u00d3scar Rilo ser\u00e1 su sustituto<\/a> aparece primero en <a href=\"https:\/\/www.hellpress.com\/\">Hellpress<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Problemas de salud aquejan al cantante del grupo de Death Metal Los brit\u00e1nicos BENEDICTION han informado de que su vocalista, Dave Ingram, no podr\u00e1 actuar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":135574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[890],"tags":[20108,2858,32094,876,19694,108,18117],"class_list":["post-135573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-benediction","tag-espanola","tag-ingram","tag-musica","tag-oscar","tag-pierde","tag-sustituto"],"_links":{"self":[{"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/posts\/135573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/comments?post=135573"}],"version-history":[{"count":0,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/posts\/135573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/media\/135574"}],"wp:attachment":[{"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/media?parent=135573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/categories?post=135573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/tags?post=135573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}