{"id":134975,"date":"2026-04-21T12:30:00","date_gmt":"2026-04-21T18:30:00","guid":{"rendered":"https:\/\/pongara.net\/news\/el-ministerio-de-sanidad-concluye-de-forma-oficial-y-para-sorpresa-de-nadie-que-la-homeopatia-no-funciona\/"},"modified":"2026-04-21T12:30:00","modified_gmt":"2026-04-21T18:30:00","slug":"el-ministerio-de-sanidad-concluye-de-forma-oficial-y-para-sorpresa-de-nadie-que-la-homeopatia-no-funciona","status":"publish","type":"post","link":"https:\/\/pongara.net\/news\/el-ministerio-de-sanidad-concluye-de-forma-oficial-y-para-sorpresa-de-nadie-que-la-homeopatia-no-funciona\/","title":{"rendered":"El Ministerio de Sanidad concluye de forma oficial, y para sorpresa de nadie, que la homeopat\u00eda no funciona"},"content":{"rendered":"<div>\n<p><img decoding=\"async\" style=\"aspect-ratio:204\/247; width:25%; float:right; margin-left:1em;\" loading=\"lazy\" src=\"https:\/\/pongara.net\/news\/wp-content\/uploads\/2026\/04\/SelloHomeopatia.jpg\" alt=\"Un sello alem\u00e1n que conmemora los 200 a\u00f1os de la homeopat\u00eda\" title=\"Una chorrada de un alem\u00e1n en un sello\">Lo dicen <a href=\"https:\/\/www.sanidad.gob.es\/gabinete\/notasPrensa.do?id=6893\">un poco m\u00e1s en fino<\/a>, pero el mensaje es el mismo: <strong>El Ministerio de Sanidad concluye que no existe evidencia cient\u00edfica que avale la eficacia de la homeopat\u00eda en ninguna patolog\u00eda<\/strong>.<\/p>\n<p>Por sin ha salido a la luz el informe sobre la homeopat\u00eda de la Agencia Espa\u00f1ola de Medicamentos y Productos Sanitarios (AEMPS) que el ministerio hab\u00eda prometido hace no s\u00e9 ya ni cu\u00e1nto tiempo, <a href=\"https:\/\/www.aemps.gob.es\/informa\/docs\/informe-homeopatia-2026.pdf\"><strong>Homeopat\u00eda y productos homeop\u00e1ticos: Evaluaci\u00f3n de las evidencias acerca de su eficacia y seguridad<\/strong><\/a> [PDF].<\/p>\n<p>Sus conclusiones:<\/p>\n<ul>\n<li><strong>No existe evidencia cient\u00edfica<\/strong> publicada que avale la eficacia de la homeopat\u00eda como un instrumento terap\u00e9utico eficaz.<\/li>\n<li>Se ha constatado en los trabajos publicados que la eficacia observada para los productos homeop\u00e1ticos <strong>es comparable al placebo<\/strong>.<\/li>\n<li>Los ciudadanos deben conocer, cuando escogen iniciar o mantener tratamientos basados en la homeopat\u00eda, que esta carece de evidencia cient\u00edfica y que <strong>pueden poner en peligro su salud<\/strong> si rechazan o sustituyen los tratamientos que la medicina basada en la evidencia les propone.<\/li>\n<\/ul>\n<p>El informe tambi\u00e9n lo cuenta pero a modo de recordatorio <a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/doce-argumentos-falsos-a-favor-de-la-homeopatia.html\">la homeopat\u00eda<\/a> es esa pseudociencia que dice que <strong>lo similar cura lo similar<\/strong> y que lo que hay que hacer para tratar a alguien es darle dosis infinitesimales del producto en cuesti\u00f3n.<\/p>\n<p>Dosis tan infinitesimales que equivaldr\u00edan, seg\u00fan dice el informe, a <strong>disolver un sobre de az\u00facar en toda el agua del Mediterr\u00e1neo<\/strong>. Dosis tan infinitesimales que en los preparados homeop\u00e1ticos no puede haber <strong>ni una mol\u00e9cula del principio activo<\/strong>. Pero se supone que da igual porque el resto del compuesto <em>de alguna manera<\/em> <strong>se impregna de sus propiedades curativas<\/strong>.<\/p>\n<p>Y eso cuando hay alg\u00fan principio activo. Porque por ejemplo <strong>la Luz de Venus<\/strong>, enfocada sobre alg\u00fan \u00abtratamiento\u00bb homeop\u00e1tico sirve para calmar los dolores menstruales.<\/p>\n<p>En cualquier caso el estudio de la AEMPS lo que ha hecho es <strong>una revisi\u00f3n sistem\u00e1tica<\/strong> de estudios acerca de la eficacia y seguridad de los productos homeop\u00e1ticos para llegar a las conclusiones expuestas arriba, que b\u00e1sicamente equivalen a que <strong>la homeopat\u00eda no sirve para nada<\/strong>.<\/p>\n<p>Y que tampoco es cierto del todo que tampoco pasa nada por tratarte con homeopat\u00eda porque en el peor de los casos <em>no te hace nada<\/em>, pues si abandonas tratamientos de eficacia contrastada por ella <strong>pones en peligro tu salud<\/strong>.<\/p>\n<p>Quiz\u00e1s ahora que sabemos <em>oficialmente<\/em> que la homeopat\u00eda no funciona sea el momento de retomar la iniciativa de los tiempos en los que Carmen Mont\u00f3n era Ministra de Sanidad de pedir a la UE que los productos homeop\u00e1ticos <a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/gobierno-espana-pedira-homeopatia-deje-de-ser-considerada-medicamento.html\"><strong>dejen de ser considerados medicamentos<\/strong><\/a>.<\/p>\n<p>Relacionado,<\/p>\n<ul>\n<li><a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/cinco-motivos-por-los-que-la-homeopatia-es-peligrosa.html\">Cinco motivos (entre muchos) por los que la homeopat\u00eda es peligrosa<\/a><\/li>\n<li><a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/james-randi-explica-homeopatia.html\">James Randi explica la homeopat\u00eda<\/a><\/li>\n<li><a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/francia-retira-financiacion-publica-homeopatia.html\">Francia decide retirar la financiaci\u00f3n p\u00fablica a la homeopat\u00eda<\/a><\/li>\n<li><a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/australia-valora-dejar-de-vender-homeopatia-en-farmacias.html\">Australia valora prohibir vender homeopat\u00eda en las farmacias<\/a><\/li>\n<li><a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/real-hospital-homeopatico-londres-fin-homeopatia.html\">El Real Hospital Homeop\u00e1tico de Londres dejar\u00e1 de poder recetar homeopat\u00eda con dinero p\u00fablico<\/a><\/li>\n<li><a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/homeopatia-urgencias.html\">Homeopat\u00eda de urgencias<\/a><\/li>\n<li><a href=\"https:\/\/www.microsiervos.com\/archivo\/humor\/homeopatia-demostrada-cientificamente-no.html\">Homeopat\u00eda: demostrada cient\u00edficamente*<\/a><\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.microsiervos.com\/archivo\/ciencia\/ministerio-salud-homeopatia-no-funciona.html\"># Enlace Permanente<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lo dicen un poco m\u00e1s en fino, pero el mensaje es el mismo: El Ministerio de Sanidad concluye que no existe evidencia cient\u00edfica que avale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":134976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14556,1595,31972,10035,2978,1268,467,10622,2139],"class_list":["post-134975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-concluye","tag-funciona","tag-homeopatia","tag-ministerio","tag-nadie","tag-noticias","tag-oficial","tag-sanidad","tag-sorpresa"],"_links":{"self":[{"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/posts\/134975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/comments?post=134975"}],"version-history":[{"count":0,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/posts\/134975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/media\/134976"}],"wp:attachment":[{"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/media?parent=134975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/categories?post=134975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pongara.net\/news\/wp-json\/wp\/v2\/tags?post=134975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}